{"id":5439,"date":"2025-09-04T21:12:42","date_gmt":"2025-09-04T19:12:42","guid":{"rendered":"https:\/\/jonpult.ch\/de\/?p=5439"},"modified":"2025-09-05T11:22:30","modified_gmt":"2025-09-05T09:22:30","slug":"den-ukrainekaempfenden-mindesten-verzeihen","status":"publish","type":"post","link":"https:\/\/jonpult.ch\/rm\/den-ukrainekaempfenden-mindesten-verzeihen\/","title":{"rendered":"Den Ukrainek\u00e4mpfenden mindestens verzeihen"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"767\" src=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657-1024x767.png.webp\" alt=\"Letztes Jahr durfte ich den Z\u00fcrcher Jona Neidhart kennenlernen. Er hat sich in der Ukraine der Internationalen Legion der Territorialverteidigung angeschlossen. Denn er ist \u00fcberzeugt, dass es seine demokratische und vor allem christliche Pflicht ist, gegen Putins Aggression zu k\u00e4mpfen. Seine Geschichte und sein pers\u00f6nliches Opfer beeindrucken mich, obwohl ich nicht religi\u00f6s bin und auch nicht in den Krieg ziehen w\u00fcrde. Doch es l\u00e4sst sich nicht bestreiten: In der Ukraine werden zentrale Werte und Interessen Europas und der Schweiz verteidigt.\" class=\"wp-image-5440\" style=\"width:1100px;height:auto\" srcset=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657-1024x767.png.webp 1024w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657-300x225.png.webp 300w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657-768x575.png.webp 768w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657-50x37.png.webp 50w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657-67x50.png.webp 67w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657-100x75.png.webp 100w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657-133x100.png.webp 133w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657-854x640.png.webp 854w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657-640x479.png.webp 640w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657-1025x768.png.webp 1025w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2025\/09\/Screenshot-2025-09-04-210657.png.webp 1092w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Screenshot, Tages-Anzeiger, 27. September 2024<\/figcaption><\/figure>\n\n\n\n<p>Letztes Jahr durfte ich den Z\u00fcrcher Jona Neidhart kennenlernen. Er hat sich in der Ukraine der Internationalen Legion der Territorialverteidigung angeschlossen. Denn er ist \u00fcberzeugt, dass es seine demokratische und vor allem christliche Pflicht ist, gegen Putins Aggression zu k\u00e4mpfen. Seine Geschichte und sein pers\u00f6nliches Opfer beeindrucken mich, obwohl ich nicht religi\u00f6s bin und auch nicht in den Krieg ziehen w\u00fcrde. Doch es l\u00e4sst sich nicht bestreiten: In der Ukraine werden zentrale Werte und Interessen Europas und der Schweiz verteidigt.<\/p>\n\n\n\n<p>Trotzdem droht Menschen wie Jona hierzulande eine Strafe. Das Milit\u00e4rstrafgesetz verbietet \u2013 ausser f\u00fcr die Schweizer Garde im Vatikan \u2013 den Eintritt in fremden Milit\u00e4rdienst. Um eine Bestrafung der Schweizer Ukrainek\u00e4mpferinnen und -k\u00e4mpfer zu verhindern, fordere ich darum eine Amnestie f\u00fcr diese Menschen. Die entsprechende Parlamentarische Initiative wird in der kommenden Session im Nationalrat behandelt.<\/p>\n\n\n\n<p>Eine Amnestie hebt keine Urteile auf, legalisiert nichts und \u00e4ndert auch das Gesetz nicht. Sie bedeutet lediglich: Der Staat verzichtet bei einer bestimmten Gruppe auf Strafe, weil deren Tat zwar illegal, aber moralisch richtig oder zumindest zu verzeihen ist. Der St. Galler Kommentar zur Bundesverfassung beschreibt sie daher auch treffend als \u00abkollektives Verzeihen\u00bb.<\/p>\n\n\n\n<p>Wer in der Ukraine k\u00e4mpft, verteidigt nicht nur deren Bev\u00f6lkerung und Territorium, sondern auch Prinzipien des V\u00f6lkerrechts und Werte der Eidgenossenschaft. Zum Beispiel die Souver\u00e4nit\u00e4t und territoriale Integrit\u00e4t aller Staaten gem\u00e4ss UNO-Charta. Oder die Sicherung des Friedens durch die Garantie der Unabh\u00e4ngigkeit und Grenzen Europas, festgeschrieben in der Schlussakte von Helsinki, dem Grundstein der OSZE. Und auch die Werte Freiheit, Demokratie und Unabh\u00e4ngigkeit, die unsere Verfassung als Staatsziele verankert.<\/p>\n\n\n\n<p>Die Ukraine verteidigt sich legitim, Russland f\u00fchrt eine verbrecherische Aggression. Es liegt deshalb im Interesse der Schweiz, jene B\u00fcrgerinnen und B\u00fcrger nicht zu bestrafen, die freiwillig und unter Einsatz ihres Lebens f\u00fcr das Recht einstehen.<\/p>\n\n\n\n<p>Oft wird die Neutralit\u00e4t gegen die Amnestie ins Feld gef\u00fchrt. Doch das Neutralit\u00e4tsrecht verpflichtet den Staat, nicht die Einzelnen. Das Haager Abkommen von 1907 h\u00e4lt ausdr\u00fccklich fest: Eine neutrale Macht ist nicht verantwortlich, wenn Einzelpersonen in den Dienst einer Kriegspartei treten. Darum kennen andere neutrale Staaten wie \u00d6sterreich oder Irland auch kein entsprechendes Verbot. Zudem ist Neutralit\u00e4t \u2013 im Gegensatz zu Freiheit, Demokratie und Unabh\u00e4ngigkeit \u2013 kein Staatsziel gem\u00e4ss unserer Verfassung.<\/p>\n\n\n\n<p>Auch ein Blick in die Geschichte zeigt, warum die Amnestie f\u00fcr die Ukrainek\u00e4mpfenden richtig ist. 1939 baten die Schweizer Spanienk\u00e4mpfer, die gegen Franco f\u00fcr die Demokratie k\u00e4mpften, das Parlament um eine Amnestie. Sie erhielten sie nicht, viele wurden hart bestraft. Erst 70 Jahre sp\u00e4ter hat das Parlament sie rehabilitiert. Das war zwar richtig, kam aber viel zu sp\u00e4t. Die meisten Betroffenen waren bereits gestorben.<\/p>\n\n\n\n<p>Diesen Fehler sollten wir nicht wiederholen. Wer f\u00fcr Freiheit und Demokratie k\u00e4mpft, verdient keine Strafe \u2013 sondern mindestens unser kollektives Verzeihen.<\/p>\n\n\n\n<p><em>Dieser Text ist am 3. September 2025 als Kolumne in der S\u00fcdostschweiz erschienen.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Letztes Jahr durfte ich den Z\u00fcrcher Jona Neidhart kennenlernen. Er hat sich in der Ukraine der Internationalen Legion der Territorialverteidigung angeschlossen. Denn er ist \u00fcberzeugt, dass es seine demokratische und vor allem christliche Pflicht ist, gegen Putins Aggression zu k\u00e4mpfen. Seine Geschichte und sein pers\u00f6nliches Opfer beeindrucken mich, obwohl ich nicht religi\u00f6s bin und auch nicht in den Krieg ziehen w\u00fcrde. Doch es l\u00e4sst sich nicht bestreiten: In der Ukraine werden zentrale Werte und Interessen Europas und der Schweiz verteidigt.<\/p>\n","protected":false},"author":1,"featured_media":5440,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"wds_primary_category":1,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/5439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/comments?post=5439"}],"version-history":[{"count":11,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/5439\/revisions"}],"predecessor-version":[{"id":5474,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/5439\/revisions\/5474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/media\/5440"}],"wp:attachment":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/media?parent=5439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/categories?post=5439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/tags?post=5439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}