{"id":4695,"date":"2024-05-01T11:12:41","date_gmt":"2024-05-01T09:12:41","guid":{"rendered":"https:\/\/jonpult.ch\/de\/?p=4695"},"modified":"2025-09-05T13:02:41","modified_gmt":"2025-09-05T11:02:41","slug":"1-mai-rede-2024-gehalten-in-buelach-uster-und-muenchenbuchsee","status":"publish","type":"post","link":"https:\/\/jonpult.ch\/rm\/1-mai-rede-2024-gehalten-in-buelach-uster-und-muenchenbuchsee\/","title":{"rendered":"Rede zum 1. Mai in B\u00fclach, Uster und M\u00fcnchenbuchsee"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-1024x684.jpg.webp\" alt=\"\" class=\"wp-image-4696\" srcset=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-1024x684.jpg.webp 1024w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-300x200.jpg.webp 300w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-768x513.jpg.webp 768w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-1536x1025.jpg.webp 1536w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-2048x1367.jpg.webp 2048w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-50x33.jpg.webp 50w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-75x50.jpg.webp 75w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-100x67.jpg.webp 100w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-150x100.jpg.webp 150w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-959x640.jpg.webp 959w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-640x427.jpg.webp 640w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-1150x768.jpg.webp 1150w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-1618x1080.jpg.webp 1618w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/05\/1.-Mai-Uster-1920x1282.jpg.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">W\u00e4hrend der Rede in Uster. Bild: Dario Vareni.<\/figcaption><\/figure>\n\n\n\n<p>\u00abLet\u2019s drink to the hard working people, let\u2019s drink to the salt of the earth\u00bb, singt Mick Jagger in der legend\u00e4ren Working-Class-Hymne der Rolling Stones. Als agnostischer Mensch habe ich Hemmungen vor Bibelzitaten. Und doch finde ich: Jagger und die Stones haben Recht.<\/p>\n\n\n\n<p>Die hart arbeitenden Menschen schaffen die Werte unserer Wirtschaft. Sie sorgen f\u00fcr Fortschritt und Sicherheit in unserer Gesellschaft. Durch sie entsteht W\u00fcrde f\u00fcr und Zugeh\u00f6rigkeit unter Menschen. <strong><\/strong><\/p>\n\n\n\n<p>Die B\u00e4hnlerinnen und Chauffeure, die Kinderg\u00e4rtner und Lehrerinnen, die Verk\u00e4uferinnen und Lageristen, die Elektroinstallateure und Polizistinnen, die Pflegerinnen und Bauarbeiter, die Sozialarbeiter und die Sanit\u00e4rinnen, die K\u00f6che und die Apothekerinnen, die Sekret\u00e4rinnen und die Strassenkehrer \u2013 sie alle und viele mehr sind es, die jeden Tag daf\u00fcr sorgen, dass unser Leben funktioniert. Mit ihrer Erwerbsarbeit einerseits und mit ihrer unbezahlten Pflege-, Erziehungs- und Betreuungsarbeit andererseits. Sie sind tats\u00e4chlich das Salz der Erde!<\/p>\n\n\n\n<p>Deshalb feiern wir sie und ihre Arbeit jedes Jahr am Tag der Arbeit, am 1. Mai. Und in den \u00fcbrigen 364 Tagen des Jahres engagieren wir uns daf\u00fcr, dass die Arbeit endlich den Respekt und die Anerkennung erh\u00e4lt, die sie verdient.<\/p>\n\n\n\n<p>F\u00fcr den sozialen Fortschritt im Arbeitsleben, in der Wirtschaft, in der Gesellschaft, in der Politik.<\/p>\n\n\n\n<p>In der Schweiz haben wir die Chance, diesen sozialen Fortschritt \u00fcber Volksabstimmungen voranzutreiben. Am 3. M\u00e4rz haben wir es dieses Jahr ein erstes Mal geschafft. Nach Jahren des Niedergangs der Pensionskassenrenten und immer h\u00f6heren Kosten f\u00fcr die Bev\u00f6lkerung bei den Mieten, den Pr\u00e4mien und der Energie \u2013 einem erheblichen Kaufkraftverlust \u2013 hat auch die Schweiz eine 13. Monatsrente eingef\u00fchrt.<\/p>\n\n\n\n<p>Ab 2026 wird 13. AHV-Rente daf\u00fcr sorgen, dass die Kaufkraftverluste der letzten Jahre f\u00fcr alle dannzumaligen und k\u00fcnftigen Rentnerinnen und Rentner ausgeglichen werden.<\/p>\n\n\n\n<p>Obwohl monatelang behauptet wurde, die 13. AHV-Rente sei unm\u00f6glich und egoistisch und w\u00fcrde die j\u00fcngere Generation massiv belasten, liessen sich die Schweizerinnen und Schweizer nicht ist Bockshorn jagen.<\/p>\n\n\n\n<p>Weil der Generationenkonflikt aber weiterhin herbeigeredet wird, will ich heute am Tag der Arbeit eines klarstellen:<\/p>\n\n\n\n<p>Historisch hat nichts das Verh\u00e4ltnis zwischen den Generationen mehr verbessert als die AHV. Sie hat auf der einen Seite der breiten Bev\u00f6lkerung ein Alter in W\u00fcrde erm\u00f6glicht. Und sie hat auf der anderen Seite die Jungen von der B\u00fcrde entlastet, auch finanziell f\u00fcr ihre Eltern sorgen zu m\u00fcssen. F\u00fcr j\u00fcngere Generationen war und ist die AHV die wohl gr\u00f6sste finanzielle Entlastungsmassnahme aller Zeiten. Diese AHV als Last f\u00fcr die Jungen zu verleumden, ist absurd. Denn bei der AHV erhalten statistisch neun von zehn Personen mehr Rente zwischen der Pensionierung und dem Lebensende, als sie im gesamten aktiven Arbeitsleben einbezahlt haben. Darum ist auch eine 13. AHV-Rente sicher keine Last f\u00fcr die Jungen sondern ein St\u00fcck Gerechtigkeit f\u00fcr Jung <em>und<\/em> Alt.<\/p>\n\n\n\n<p>Am 9. Juni haben wir die n\u00e4chste Chance, den sozialen Fortschritt voranzutreiben und etwas f\u00fcr die Kaufkraft der Menschen zu tun. Dann stimmen wir \u00fcber die Pr\u00e4mien-Initiative ab. Sie ist dringend n\u00f6tig, denn die Krankenkassenpr\u00e4mien explodieren. Das bringt immer mehr Menschen in finanzielle Schwierigkeiten. Mit einem Ja am 9. Juni stoppen wir die j\u00e4hrliche Zumutung des Pr\u00e4mienanstiegs f\u00fcr Familien, Rentnerpaare, Alleinstehende mit tiefen und mittleren Einkommen.<\/p>\n\n\n\n<p>Denn mit der Initiative w\u00fcrden die Pr\u00e4mien gedeckelt und d\u00fcrften neu nicht mehr als zehn Prozent des verf\u00fcgbaren Einkommens eines Haushalts ausmachen. Damit sch\u00fctzen wir insbesondere die hart arbeitende Mittelschicht vor der einzigen, j\u00e4hrlich steigenden Steuer in unserem Land. Und erst noch der unsozialsten \u2013 einer Kopfpr\u00e4mie! Erstaunlich, dass ausgerechnet diejenigen, die sonst immer behaupten, die \u00abSteuerbelastung des Mittelstandes\u00bb senken zu wollen, bei der f\u00fcr die Mittelschicht schlimmsten, j\u00e4hrlich steigenden Steuer gegen Entlastung sind.<\/p>\n\n\n\n<p>Sie ziehen auch in diesem Abstimmungskampf durch das Land und machen den Menschen Angst. Wir k\u00f6nnten uns den Pr\u00e4miendeckel nicht leisten, die Kosten seien zu hoch. Das ist Quatsch. Die Pr\u00e4mien-Initiative verursacht keinen einzigen Rappen Mehrkosten. Sie sorgt einfach daf\u00fcr, dass die bestehenden und k\u00fcnftigen Kosten ein wenig gerechter verteilt werden.<\/p>\n\n\n\n<p>Statt dass die Kosten unserer Gesundheitsversicherung voll bei der Mittelschicht und bei den Familien bleiben, sorgen wir mit einem Ja zur Pr\u00e4mien-Initiative daf\u00fcr, dass jeder Franken \u00fcber der Schwelle von 10% des jeweiligen Haushaltseinkommens durch die Allgemeinheit und damit sozial finanziert wird.<\/p>\n\n\n\n<p>Die Frage ist einfach: Wollen wir, dass alle k\u00fcnftigen Kostensteigerungen im Gesundheitswesen einfach \u00fcber Pr\u00e4mienerh\u00f6hungen von der hart arbeitenden Mittelschicht getragen werden? Oder soll der Staat, der dank den progressiven Steuern viel st\u00e4rker von den Reichen und Superreichen finanziert wird, seinen korrekten Beitrag leistet?<\/p>\n\n\n\n<p>Die zweite Option ist ein offensichtliches Gebot der Gerechtigkeit. In keinem Land Europas m\u00fcssen die Menschen mehr aus der eigenen Tasche f\u00fcr die Gesundheitskosten zahlen als in der Schweiz. Wegen unseren Kopfpr\u00e4mien, wegen unseren im Schnitt hohen Franchisen und wegen der Tatsache, dass einige Leistungen wie die Zahnmedizin durch die obligatorische Krankenversicherung nicht gedeckt sind.<\/p>\n\n\n\n<p>Im europ\u00e4ischen Schnitt werden 76% der Gesundheitskosten \u00fcber einkommensabh\u00e4ngige Steuern oder Lohnbeitr\u00e4ge finanziert. In der Schweiz sind wir bei l\u00e4ppischen 36%. Die Pr\u00e4mien-Initiative w\u00fcrde dieses schiefe Verh\u00e4ltnis moderat verbessern.<\/p>\n\n\n\n<p>Die Pr\u00e4mien-Initiative ist also wirklich keine Revolution, sie ist eine soziale Notwendigkeit. Wir alle m\u00fcssen uns f\u00fcr ein Ja am 9. Juni engagieren!<\/p>\n\n\n\n<p>Nun wenden unsere Gegner ein, dass der soziale Fortschritt einer 13. AHV-Rente und des dringend notwendigen Pr\u00e4miendeckels die Staatskassen mehr belasten, was angesichts der \u00abangespannten Finanzlage\u00bb unverantwortlich sei. Auch dieses Argument ist falsch. Die Staatfinanzen in der Schweiz sind nicht angespannt. Im Gegenteil. Fast alle Kantone schreiben Gewinne. Und sowohl der Bund als auch die meisten Kantone haben einen so tiefen Schuldenstand, dass keine vern\u00fcnftige \u00d6konomin darauf kommen w\u00fcrde, die Schweiz sei ein Fall f\u00fcr Sparmassnahmen. Das einzige Finanzprobleme, welches unser Land tats\u00e4chlich hat, ist der Schuldenbremsenfetischismus der rechten Parteien.<\/p>\n\n\n\n<p>Als Bund haben wir eine Nettoverschuldung im Verh\u00e4ltnis zur Wirtschaftsleistung von 17.8%, das ist l\u00e4cherlich tief. Wir k\u00f6nnten diese Schuld auf einen Schlag verdoppeln und h\u00e4tten bei allen Ratingagenturen immer noch die Bestnote AAA. Die fiskalisch sehr konservativen \u00d6konominnen und \u00d6konomen, welche die Maastrichter Kriterien ausgearbeitet haben, definieren eine Schuldenquote von bis zu 60% als gesund \u2013 und wir haben nicht einmal 18%!<\/p>\n\n\n\n<p>Nat\u00fcrlich sind Schulden nicht per se anstrebenswert und es w\u00e4re kl\u00fcger, zus\u00e4tzliche Aufwendungen des Staates mit klugen Steuern auf dem Kapital, auf grossen Erbschaften oder auf Finanztransaktionen zu finanzieren. Aber ein reales Finanzproblem haben wir auch ohne diese sinnvollen Steuern definitiv nicht. Wir haben ein rein ideologisches Problem bei der rechten Mehrheit im Bundesrat und im Parlament.&nbsp;<\/p>\n\n\n\n<p>Am 9. Juni stimmen wir auch \u00fcber das Stromgesetz ab. Auch diese Abstimmung ist wichtig f\u00fcr eine soziale Schweiz. Denn ein Ja zum Stromgesetz ist notwendig, um unsere Klimaziele erreichen. Und Klimaschutz ist auch eine soziale Notwendigkeit. Weil wir wissen, dass es in einer kaputten Natur keine gute Arbeit und keine soziale Gerechtigkeit geben kann. Ausserdem wissen wir, dass nur eine sichere Energieversorgung mit erneuerbarem Strom stabile und bezahlbare Energiepreise in Zukunft sichern kann. Die drei gr\u00f6ssten Kaufkraftkiller sind die Mieten, die Pr\u00e4mien und eben die Energiekosten. Damit wir in Zukunft die Energiekosten f\u00fcr die Bev\u00f6lkerung unter Kontrolle behalten, m\u00fcssen wir im grossen Stil erneuerbare Energien zubauen. Auch das schaffen wir mit einem Ja zum Stromgesetz am 9. Juni.<\/p>\n\n\n\n<p>F\u00fcr dauerhaften sozialen Fortschritt braucht es aber nicht nur punktuelle Erfolge bei Abstimmungen. Die Herausforderung ist gr\u00f6sser. Es braucht ein kollektives Bewusstsein daf\u00fcr, dass die gesellschaftlichen Verh\u00e4ltnisse keine Naturereignisse sind, sondern das Resultat von politischen Entscheidungen. Es ist zum Beispiel nicht einfach Schicksal, dass in der wohlhabenden Schweiz zugleich gegen 900\u2019000 Menschen in Armut leben, w\u00e4hrend die 300 Reichsten ein Verm\u00f6gen von gegen 900 Milliarden \u2013 mehr als das Zehnfache des Bundesbudgets \u2013 besitzen.<\/p>\n\n\n\n<p>Diese ungeheure Ungleichheit ist das Resultat einer unsozialen Politik. Und deshalb kann sie auch \u00fcberwunden werden. Aber wir m\u00fcssen uns daf\u00fcr engagieren: politisch, gewerkschaftlich, im Alltag. Damit mehr Menschen erkennen, dass sie Teil einer solidarischen Ver\u00e4nderung sein k\u00f6nnen. Das ist letztlich die Idee der sozialen Demokratie, f\u00fcr die der Tag der Arbeit steht.<\/p>\n\n\n\n<p>Wie ihr wisst, ist der 1. Mai der einzig wirklich globale Feiertag. Denn der Kampf der Arbeiterinnen und Arbeiter um W\u00fcrde, Freiheit und Gerechtigkeit war und ist ein weltweiter.<\/p>\n\n\n\n<p>Darum schliesse ich mit einigen Gedanken an unsere Mitstreiterinnen und Mitstreiter in anderen Teilen der Welt.<\/p>\n\n\n\n<p>Ich m\u00f6chte an die Aktivistinnen und Aktivisten erinnern, die in gef\u00e4hrlichen und unfreien Teilen der Welt ihr Leben riskieren, um sich f\u00fcr Freiheit, sozialen Fortschritt, Gerechtigkeit, Frieden und Menschenrechte einzusetzen. Vor einem Monat durfte ich mit dem Hilfswerk Swissaid und sechs Kolleginnen und Kollegen aus dem Nationalrat Kolumbien bereisen. Obwohl das Land in Europa mittlerweile als \u00abPost-Conflict\u00bb und \u00abMiddle-Income Country\u00bb gilt, ist die Ungleichheit und damit auch die Armut riesig und es sterben immer noch t\u00e4glich viele Menschen an der Gewalt von bewaffneten Gruppen. Aber die lebendige Zivilgesellschaft leistet Widerstand gegen die Gewalt. Diese lebendige Zivilgesellschaft engagiert sich f\u00fcr einen dauerhaften Frieden, der auf sozialer Gerechtigkeit gebaut wird.<\/p>\n\n\n\n<p>Wir haben die 26-j\u00e4hrige indigene Yina Ortega Benitez kennengelernt, die als Jugendliche ihr Heimatdorf verlassen musste, weil ihr dort die Zwangsprostitution oder die Zwangsrekrutierung durch eine bewaffnete Gruppe gedroht h\u00e4tte. Dank Swissaid konnte sie studieren und hat heute eine gute Arbeit.<\/p>\n\n\n\n<p>Yina ist zudem Jugendaktivistin und Jungpolitikerin, in der Schweiz w\u00e4re sie wohl in der JUSO. W\u00e4hrend hiesige Jusos relativ unbeschwert politisieren k\u00f6nnen, muss sich Yina immer wieder verstecken, weil ihr Leben bedroht wird. Die bewaffneten Gruppen wollen nicht, dass sie den Jugendlichen hilft, sich aus den F\u00e4ngen der Gewaltkultur und der bewaffneten Gruppen zu l\u00f6sen.<\/p>\n\n\n\n<p>Obwohl sie alles riskiert, ist Aufgeben f\u00fcr die junge Frau keine Option. Sie will mit ihren Freundinnen und Freunden weiter f\u00fcr den Frieden und f\u00fcr die sozialen Rechte der Jugend k\u00e4mpfen. Dabei hat ihre Organisation eine klare Vorstellung f\u00fcr ihre Friedensarbeit. Sie schreiben einen wunderbaren Satz:<\/p>\n\n\n\n<p><em>\u00abFrieden ist nicht die Abwesenheit von bewaffnetem Konflikt \u2013 Frieden herrscht erst, wenn die Menschen wieder ein Recht auf Bildung, auf gute Arbeit, auf Sicherheit und Entscheidungs- und Bewegungsfreiheit haben.\u00bb<\/em><\/p>\n\n\n\n<p>Unsere Gedanken sind heute bei allen Yinas dieser Welt. Und auch bei allen unschuldigen Menschen, die an den schrecklichen Kriegen und Konflikten leiden: In der Ukraine, in Gaza, im Yemen, im Sudan, in Myanmar aber auch in allen \u00fcbrigen rund 90 bewaffneten Konflikten, die wir nicht t\u00e4glich auf dem Radar haben.<\/p>\n\n\n\n<p>Freiheit, Frieden, sozialer Fortschritt, Gerechtigkeit und Menschenrechte. Letztlich sind das die Werte, die den 1. Mai \u00fcberall auf der Welt ausmachen. Diese Werte stellen die Hoffnung f\u00fcr eine bessere Zukunft dar. Sie fallen aber nicht vom Himmel. Wir m\u00fcssen uns f\u00fcr diese Werte engagieren. Am Tag der Arbeit und an jedem anderen Tag. Tun wir es mit Freude, tun wir es zusammen.<\/p>\n\n\n\n<p>Es lebe der 1. Mai \u2013 hoch die internationale Solidarit\u00e4t!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLet\u2019s drink to the hard working people, let\u2019s drink to the salt of the earth\u00bb, singt Mick Jagger in der legend\u00e4ren Working-Class-Hymne der Rolling Stones. Als agnostischer Mensch habe ich Hemmungen vor Bibelzitaten. Und doch finde ich: Jagger und die Stones haben Recht.<\/p>\n<p>Die hart arbeitenden Menschen schaffen die Werte unserer Wirtschaft. Sie sorgen f\u00fcr Fortschritt und Sicherheit in unserer Gesellschaft. Durch sie entsteht W\u00fcrde f\u00fcr und Zugeh\u00f6rigkeit unter Menschen. <\/p>\n<p>Die B\u00e4hnlerinnen und Chauffeure, die Kinderg\u00e4rtner und Lehrerinnen, die Verk\u00e4uferinnen und Lageristen, die Elektroinstallateure und Polizistinnen, die Pflegerinnen und Bauarbeiter, die Sozialarbeiter und die Sanit\u00e4rinnen, die K\u00f6che und die Apothekerinnen, die Sekret\u00e4rinnen und die Strassenkehrer \u2013 sie alle und viele mehr sind es, die jeden Tag daf\u00fcr sorgen, dass unser Leben funktioniert. Mit ihrer Erwerbsarbeit einerseits und mit ihrer unbezahlten Pflege-, Erziehungs- und Betreuungsarbeit andererseits. Sie sind tats\u00e4chlich das Salz der Erde!<\/p>\n","protected":false},"author":1,"featured_media":4696,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"wds_primary_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/4695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/comments?post=4695"}],"version-history":[{"count":4,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/4695\/revisions"}],"predecessor-version":[{"id":5493,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/4695\/revisions\/5493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/media\/4696"}],"wp:attachment":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/media?parent=4695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/categories?post=4695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/tags?post=4695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}