{"id":4603,"date":"2024-02-21T16:35:50","date_gmt":"2024-02-21T15:35:50","guid":{"rendered":"https:\/\/jonpult.ch\/de\/?p=4603"},"modified":"2025-09-05T13:04:57","modified_gmt":"2025-09-05T11:04:57","slug":"eine-13-ahv-rente-ist-angezeigt-nicht-ein-hoeheres-rentenalter","status":"publish","type":"post","link":"https:\/\/jonpult.ch\/rm\/eine-13-ahv-rente-ist-angezeigt-nicht-ein-hoeheres-rentenalter\/","title":{"rendered":"Eine 13. AHV-Rente ist angezeigt, nicht ein h\u00f6heres Rentenalter"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/02\/Testimonial-1024x538.png.webp\" alt=\"\" class=\"wp-image-4604\" srcset=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/02\/Testimonial-1024x538.png.webp 1024w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/02\/Testimonial-300x158.png.webp 300w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/02\/Testimonial-768x403.png.webp 768w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/02\/Testimonial-50x26.png.webp 50w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/02\/Testimonial-95x50.png.webp 95w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/02\/Testimonial-100x53.png.webp 100w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/02\/Testimonial-190x100.png.webp 190w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/02\/Testimonial-640x336.png.webp 640w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2024\/02\/Testimonial.png.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Die Krankenkassenpr\u00e4mien explodieren, die Mieten steigen, Energie und Lebensmittel werden teurer. Die Kaufkraft der Bev\u00f6lkerung bricht weg, weil L\u00f6hne und Renten mit der genannten Entwicklung nicht mithalten. In der Altersvorsorge kommt das Problem hinzu, dass die Pensionskassenrenten seit Jahren sinken. F\u00fcnfzehn Prozent der heutigen Rentenbeziehenden leben in einem Haushalt mit h\u00f6chstens 10\u2019000\u00a0Franken finanzieller Reserve und rund 300&#8217;000 sind armutsgef\u00e4hrdet. F\u00fcr zu viele reicht die Rente nicht mehr. Und auch viele heutige und k\u00fcnftige Rentner:innen der Mittelschicht blicken finanziell in eine schwierige Zukunft. Kein Wunder ist die 13. AHV-Rente eine sehr popul\u00e4re Forderung!<\/p>\n\n\n\n<p>\u00dcber die entsprechende Volksinitiative der Gewerkschaften stimmen wir am 3. M\u00e4rz ab. Eine 13. Monatsrente bringt zus\u00e4tzlich 1\u2019225 bis 2\u2019450&nbsp;Franken f\u00fcr Einzelpersonen und bis zu 3\u2019675&nbsp;Franken f\u00fcr Ehepaare pro Jahr. Ein angemessener Ausgleich f\u00fcr den erw\u00e4hnten Kaufkraftverlust.<\/p>\n\n\n\n<p>Die Gegner:innen f\u00fchren zwei Argumente gegen diese Volksinitiative ins Feld. Zum einen sagen sie, es w\u00fcrden auch Menschen profitieren, die es nicht n\u00f6tig h\u00e4tten. Dabei ist die viel kritisierte Giesskanne gerade das Wesen der AHV. Alle bekommen nach der Pensionierung AHV, auch Reiche und Superreiche. Aber niemand bekommt mehr als die Maximalrente von 2&#8217;450 Franken. Hingegen kennt die Finanzierung \u00fcber die Lohnprozente keinen Deckel. Darum ist die AHV die einzige S\u00e4ule der Altersvorsorge, von der die Reichen genau nicht profitieren. Die acht Prozent der Bev\u00f6lkerung, die am meisten verdienen, zahlen \u00fcber ein Arbeitsleben statistisch mehr ein, als sie bis zum Lebensende ausbezahlt bekommen. Die \u00fcbrigen 92 Prozent erhalten mehr, als sie einzahlen. Ob es nun zw\u00f6lf oder dreizehn Monatsrenten gibt, \u00e4ndert nichts an diesem fantastischen Kosten-Nutzen-Verh\u00e4ltnis f\u00fcr die \u00fcberw\u00e4ltigende Mehrheit der Bev\u00f6lkerung.<\/p>\n\n\n\n<p>Das zweite Gegenargument lautet, wir k\u00f6nnten uns eine zus\u00e4tzliche Monatsrente nicht leisten. Auch dieses sticht nicht. Im Moment nimmt die AHV deutlich mehr ein, als sie ausgibt. Die Reserve zum Jahreswechsel betrug rund 50 Milliarden Franken. Bis 2030 kann man die 13. Rente wohl ohne Zusatzfinanzierung decken. Und danach w\u00fcrde eine moderate Erh\u00f6hung der Lohnprozente ausreichen, um die 13. Rente zu finanzieren. \u00dcber 90 Prozent der Bev\u00f6lkerung w\u00fcrden unter dem Strich immer noch mehr Rente bekommen, als sie einbezahlt h\u00e4tten. Der 13. AHV-Rente k\u00f6nnen wir also trotz Panikmache der AHV-Schlechtredner mit gutem Gewissen zustimmen. <\/p>\n\n\n\n<p>Am gleichen Tag stimmen wir auch \u00fcber die Renteninitiative der Jungfreisinnigen ab, die das Rentenalter in einem ersten Schritt auf 66 Jahre erh\u00f6hen und es anschliessend an die durchschnittliche Lebenserwartung koppeln will. Das Anliegen ist aus mindestens drei Gr\u00fcnden abgehoben und unsozial.<\/p>\n\n\n\n<p>Erstens: Ein h\u00f6heres Rentenalter trifft real nur die tiefen und mittleren Einkommen. Wer es sich leisten kann, l\u00e4sst sich in den meisten F\u00e4llen so oder so fr\u00fcher pensionieren. Wenn das Rentenalter steigt, m\u00fcssen also Detailhandelsangestellte oder Pflegefachpersonen noch l\u00e4nger arbeiten, w\u00e4hrend Investmentbankerinnen oder Professoren weiterhin in Fr\u00fchpension gehen k\u00f6nnen. Das ist doppelt ungerecht, weil die Lebenserwartung von Menschen mit tiefen Einkommen geringer ist. Die Initiative trifft also diejenigen am st\u00e4rksten, die h\u00e4rter arbeiten, tendenziell bei schlechterer Gesundheit sind und ohnehin weniger lang Rente beziehen k\u00f6nnen.<\/p>\n\n\n\n<p>Zweitens: Ein Jahr vor dem aktuell geltenden Rentenalter arbeitet nur noch die H\u00e4lfte der Menschen. Sehr viele unfreiwillig. Auf dem Arbeitsmarkt sind die Perspektiven f\u00fcr \u00e4ltere Arbeitnehmende schlecht, weil zu wenige Arbeitgeber ihnen eine Chance geben. Eine Erh\u00f6hung des Rentenalters w\u00fcrde diese entw\u00fcrdigende Situation noch versch\u00e4rfen.<\/p>\n\n\n\n<p>Drittens: Ein h\u00f6heres Rentenalter bedeutet, l\u00e4nger zu arbeiten und weniger lang Rente zu beziehen \u2013 faktisch also eine weitere Rentenk\u00fcrzung. Dabei br\u00e4uchten viele Rentenbeziehenden wie erw\u00e4hnt endlich einen Ausgleich f\u00fcr die h\u00f6heren Kosten und die Ausf\u00e4lle bei der ersten S\u00e4ule.<\/p>\n\n\n\n<p>Die Initianten argumentieren, dass wir die Erh\u00f6hung des Rentenalters brauchen, um die Finanzierung der AHV zu sichern. Die Alterung der Gesellschaft w\u00fcrde uns gewissermassen dazu zwingen. Denn bei der AHV-Gr\u00fcndung sei das Verh\u00e4ltnis zwischen den Aktiven und den Rentenbeziehenden noch 6:1 gewesen, w\u00e4hrend es heute bei 3:1 und schon bald bei 2:1 liege. Doch diese Aussage stimmt nicht. In der Gr\u00fcnderzeit der AHV gab es nie sechs Aktive, die eine Person in Rente finanzierten. Denn in den 50er-Jahren gab es nur ganz wenige Frauen, die f\u00fcr Lohn arbeiteten. In der damaligen patriarchalen Gesellschaft mussten die meisten Frauen zuhause bleiben, weshalb praktisch nur die M\u00e4nner die AHV finanzierten durften. Das ist heute zum Gl\u00fcck anders. Die grosse Mehrheit der Frauen ist berufst\u00e4tig und finanziert die AHV mit. Das kompensiert die steigende Anzahl der Rentenbeziehenden zu einem erheblichen Teil.   <\/p>\n\n\n\n<p>Fazit: Die Bev\u00f6lkerung sollte sich nicht von der Panikmache der AHV-Schlechtredner beeinflussen lassen. Eine 13. AHV-Rente ist angezeigt, sicher nicht ein h\u00f6heres Rentenalter!<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plakatw\u00e4nde, Inserate, Instagram-Posts und die meisten Medienkommentare behaupten, dass eine 13. AHV-Rente die j\u00fcngere Generation belasten wird. Dieses Narrativ ist geschichtsvergessen und falsch.<\/p>\n<p>Historisch hat nichts das Verh\u00e4ltnis zwischen den Generationen mehr verbessert als die AHV. Sie hat der breiten Bev\u00f6lkerung ein Alter in W\u00fcrde erm\u00f6glicht. Und sie hat die Jungen von der B\u00fcrde entlastet, finanziell f\u00fcr ihre Eltern sorgen zu m\u00fcssen. F\u00fcr j\u00fcngere Generationen war und ist die AHV die wohl gr\u00f6sste finanzielle Entlastungsmassnahme aller Zeiten. Diese AHV als Last f\u00fcr die Jungen zu verleumden, ist absurd.<\/p>\n","protected":false},"author":1,"featured_media":4604,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"wds_primary_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/4603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/comments?post=4603"}],"version-history":[{"count":4,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/4603\/revisions"}],"predecessor-version":[{"id":5497,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/4603\/revisions\/5497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/media\/4604"}],"wp:attachment":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/media?parent=4603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/categories?post=4603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/tags?post=4603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}