{"id":2336,"date":"2021-09-09T10:36:13","date_gmt":"2021-09-09T08:36:13","guid":{"rendered":"https:\/\/jonpult.ch\/de\/?p=2336"},"modified":"2025-09-05T13:23:16","modified_gmt":"2025-09-05T11:23:16","slug":"ehe-fuer-alle-die-das-wollen","status":"publish","type":"post","link":"https:\/\/jonpult.ch\/rm\/ehe-fuer-alle-die-das-wollen\/","title":{"rendered":"Ehe f\u00fcr alle (die das wollen), ist \u00fcberf\u00e4llig"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/jonpult.ch\/wp-content\/uploads\/2021\/09\/image001-3-1024x1024-1.jpg\" alt=\"\" class=\"wp-image-2338\" srcset=\"https:\/\/jonpult.ch\/wp-content\/uploads\/2021\/09\/image001-3-1024x1024.png 1024w, https:\/\/jonpult.ch\/wp-content\/uploads\/2021\/09\/image001-3-300x300-1.jpg 300w, https:\/\/jonpult.ch\/wp-content\/uploads\/2021\/09\/image001-3-150x150.png 150w, https:\/\/jonpult.ch\/wp-content\/uploads\/2021\/09\/image001-3-768x768.png 768w, https:\/\/jonpult.ch\/wp-content\/uploads\/2021\/09\/image001-3-50x50.png 50w, https:\/\/jonpult.ch\/wp-content\/uploads\/2021\/09\/image001-3-100x100.png 100w, https:\/\/jonpult.ch\/wp-content\/uploads\/2021\/09\/image001-3-640x640.png 640w, https:\/\/jonpult.ch\/wp-content\/uploads\/2021\/09\/image001-3-960x960-1.jpg 960w, https:\/\/jonpult.ch\/wp-content\/uploads\/2021\/09\/image001-3.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Kampagne f\u00fcr die Ehe f\u00fcr alle<\/figcaption><\/figure>\n\n\n\n<p>Zur Schliessung einer Ehe kann man mit vielen guten Gr\u00fcnden Ja oder Nein sagen. Aber es gibt keinen einzigen guten Grund, warum nicht alle Menschen das Recht haben sollten, diesen Entscheid frei zu treffen. Es ist Zeit, dass wir damit aufh\u00f6ren, unsere queeren Mitmenschen zu diskriminieren. Wir wollen eine Schweiz, die Liebe respektiert und alle Menschen als Freie und Gleiche behandelt. Darum ist ein Ja zur Ehe f\u00fcr alle am 26. September einfach \u00fcberf\u00e4llig!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zur Schliessung einer Ehe kann man mit vielen guten Gr\u00fcnden Ja oder Nein sagen. Aber es gibt keinen einzigen guten Grund, warum nicht alle Menschen das Recht haben sollten, diesen Entscheid frei zu treffen. Es ist Zeit, dass wir damit aufh\u00f6ren, unsere queeren Mitmenschen zu diskriminieren. Wir wollen eine Schweiz, die Liebe respektiert und alle Menschen als Freie und Gleiche behandelt. Darum ist ein Ja zur Ehe f\u00fcr alle am 26. September einfach \u00fcberf\u00e4llig!<\/p>\n","protected":false},"author":1,"featured_media":2338,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"wds_primary_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/2336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/comments?post=2336"}],"version-history":[{"count":5,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/2336\/revisions"}],"predecessor-version":[{"id":5527,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/2336\/revisions\/5527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/media\/2338"}],"wp:attachment":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/media?parent=2336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/categories?post=2336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/tags?post=2336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}