{"id":1940,"date":"2020-07-14T22:16:52","date_gmt":"2020-07-14T20:16:52","guid":{"rendered":"https:\/\/jonpult.ch\/de\/?p=1940"},"modified":"2025-09-05T13:38:01","modified_gmt":"2025-09-05T11:38:01","slug":"fortschritt-statt-etikettenschwindel","status":"publish","type":"post","link":"https:\/\/jonpult.ch\/rm\/fortschritt-statt-etikettenschwindel\/","title":{"rendered":"Fortschritt statt Etikettenschwindel"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"767\" height=\"365\" src=\"https:\/\/jonpult.ch\/wp-content\/uploads\/2020\/07\/Kinderabzug-Bschiss.png\" alt=\"\" class=\"wp-image-1942\" srcset=\"https:\/\/jonpult.ch\/wp-content\/uploads\/2020\/07\/Kinderabzug-Bschiss.png 767w, https:\/\/jonpult.ch\/wp-content\/uploads\/2020\/07\/Kinderabzug-Bschiss-300x143.png 300w, https:\/\/jonpult.ch\/wp-content\/uploads\/2020\/07\/Kinderabzug-Bschiss-50x24.png 50w, https:\/\/jonpult.ch\/wp-content\/uploads\/2020\/07\/Kinderabzug-Bschiss-105x50.png 105w, https:\/\/jonpult.ch\/wp-content\/uploads\/2020\/07\/Kinderabzug-Bschiss-100x48.png 100w, https:\/\/jonpult.ch\/wp-content\/uploads\/2020\/07\/Kinderabzug-Bschiss-210x100.png 210w, https:\/\/jonpult.ch\/wp-content\/uploads\/2020\/07\/Kinderabzug-Bschiss-640x305.png 640w\" sizes=\"(max-width: 767px) 100vw, 767px\" \/><figcaption>Kampagne der SP Schweiz gegen den &#8220;Kinderabzug-Bschiss&#8221;.<\/figcaption><\/figure>\n\n\n\n<p>Unser Land braucht familienfreundliche Reformen. Denn die Schweiz schneidet im europ\u00e4ischen Vergleich miserabel ab, wenn es um die Vereinbarkeit von Familie und Beruf geht. Das ist ein Hauptgrund f\u00fcr unseren R\u00fcckstand bei der Gleichstellung. Dagegen sind im letzten Jahr hunderttausende Frauen und einige solidarische M\u00e4nner auf die Strasse gegangen.<\/p>\n\n\n\n<p>Die Kinderbetreuung kostet viel zu viel, die Lohnungleichheit zwischen Frau und Mann ist noch immer stossend und uns fehlt eine gemeinsame Elternzeit. Deshalb arbeiten in zu vielen F\u00e4llen V\u00e4ter Vollzeit und M\u00fctter Teilzeit. Ob sie das nun urspr\u00fcnglich gewollt haben oder nicht. Im Mutterschaftsurlaub, den die Frau weitgehend allein verbringt, verfestigen sich herk\u00f6mmliche Muster. Die Mutter wird zur Erziehungsexpertin, der Vater bleibt famili\u00e4re Hilfskraft. Dies f\u00fchrt wiederum dazu, dass der Arbeitsmarkt Frauen benachteiligt, was zu Lohnungleichheit f\u00fchrt. Dieser Teufelskreis erfasst auch Familien, die sich eigentlich vorgenommen haben, eine gleichberechtigte Aufgabenteilung zu leben. Das Resultat ist Frust.<\/p>\n\n\n\n<p>Am 27. September d\u00fcrfen wir endlich wieder abstimmen. Bei zwei von f\u00fcnf eidgen\u00f6ssischen Abstimmungen geht es um Familienpolitik.Leisten die Vorlage \u00abSteuerliche Ber\u00fccksichtigung von Kinderdrittbetreuungskosten\u00bb sowie der indirekte Gegenvorschlag zur Volksinitiative \u00abF\u00fcr einen vern\u00fcnftigen Vaterschaftsurlaub\u00bb einen Beitrag zum familienpolitischen Fortschritt? Die Antwort ist einfach: ein grosses Nein zur ersten und ein kleines Ja zur zweiten Vorlage.<\/p>\n\n\n\n<p>Die steuerpolitische Reform, welche die Kinder- und Betreuungsabz\u00fcge auf der Bundessteuer massiv erh\u00f6hen w\u00fcrde, ist ein familienpolitischer Etikettenschwindel. Der Allgemeinheit w\u00fcrden jedes Jahr 370 Millionen Franken Einnahmen fehlen. Gelder, die direkt auf den Konten der reichsten Familien landen w\u00fcrde. Nur 6 Prozent (!) der Haushalte in der Schweiz w\u00fcrden von dieser Umverteilung profitieren. Denn damit sich die neuen Abz\u00fcge lohnen, m\u00fcssen verheiratete Eltern mindestens 190&#8217;000 Franken verdienen, Paare im Konkubinat sogar 300&#8217;000 Franken. Bundesrat Ueli Maurer sprach im Parlament Klartext: \u00abSie entlasten hier weder den Mittelstand noch wirklich Familien, sondern Sie entlasten Haushalte mit hohen Einkommen\u00bb. Wenn die Familien und die \u00fcbrigen Steuerzahlenden diesen Schwindel durchschauen, hat die Vorlage keine Chance.<\/p>\n\n\n\n<p>Was Familien wirklich brauchen, sind mehr bezahlbare Kinderbetreuungsangebote. Gerade f\u00fcr Familien der Mittelschicht sind die Betreuungskosten oft so hoch, dass sich gr\u00f6ssere Arbeitspensen f\u00fcr M\u00fctter nicht lohnen. Das verhindert gleichberechtigte Familienmodelle und verschwendet das berufliche Potential vieler Frauen.<\/p>\n\n\n\n<p>Was Familien auch brauchen, ist eine gemeinsame Elternzeit. Sie schafft gleiche Bedingungen f\u00fcr M\u00fctter und V\u00e4ter \u2013 Zuhause und auf dem Arbeitsmarkt. In diesem Zusammenhang sind die zwei Wochen Vaterschaftsurlaub, welche das Parlament als indirekten Gegenvorschlag zur Volksinitiative beschlossen hat, ein kleiner Schritt in die richtige Richtung. Er wird eine Mehrheit finden. Weitere Fortschritte bei der Vereinbarkeit von Beruf und Familie sind aber n\u00f6tig. Sonst bleibt die Schweiz ein familienpolitisches Entwicklungsland.<\/p>\n\n\n\n<p><em>Dieser Text ist am 15. Juli 2020 als Kolumne in der S\u00fcdostschweiz erschienen.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unser Land braucht familienfreundliche Reformen. Denn die Schweiz schneidet im europ\u00e4ischen Vergleich miserabel ab, wenn es um die Vereinbarkeit von Familie und Beruf geht. Das ist ein Hauptgrund f\u00fcr unseren R\u00fcckstand bei der Gleichstellung. Dagegen sind im letzten Jahr hunderttausende Frauen und einige solidarische M\u00e4nner auf die Strasse gegangen.<\/p>\n<p>Die Kinderbetreuung kostet viel zu viel, die Lohnungleichheit zwischen Frau und Mann ist noch immer stossend und uns fehlt eine gemeinsame Elternzeit. Deshalb arbeiten in zu vielen F\u00e4llen V\u00e4ter Vollzeit und M\u00fctter Teilzeit. Ob sie das nun urspr\u00fcnglich gewollt haben oder nicht. Im Mutterschaftsurlaub, den die Frau weitgehend allein verbringt, verfestigen sich herk\u00f6mmliche Muster. Die Mutter wird zur Erziehungsexpertin, der Vater bleibt famili\u00e4re Hilfskraft. Dies f\u00fchrt wiederum dazu, dass der Arbeitsmarkt Frauen benachteiligt, was zu Lohnungleichheit f\u00fchrt. Dieser Teufelskreis erfasst auch Familien, die sich eigentlich vorgenommen haben, eine gleichberechtigte Aufgabenteilung zu leben. Das Resultat ist Frust.<\/p>\n","protected":false},"author":1,"featured_media":1942,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"wds_primary_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/1940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/comments?post=1940"}],"version-history":[{"count":4,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/1940\/revisions"}],"predecessor-version":[{"id":5556,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/posts\/1940\/revisions\/5556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/media\/1942"}],"wp:attachment":[{"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/media?parent=1940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/categories?post=1940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jonpult.ch\/rm\/wp-json\/wp\/v2\/tags?post=1940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}