{"id":5612,"date":"2025-10-30T21:59:34","date_gmt":"2025-10-30T20:59:34","guid":{"rendered":"https:\/\/jonpult.ch\/de\/?p=5612"},"modified":"2025-11-04T22:11:07","modified_gmt":"2025-11-04T21:11:07","slug":"medienmacht-gehoert-nicht-in-konzernhaende","status":"publish","type":"post","link":"https:\/\/jonpult.ch\/it\/medienmacht-gehoert-nicht-in-konzernhaende\/","title":{"rendered":"Medienmacht geh\u00f6rt nicht in Konzernh\u00e4nde"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"439\" src=\"https:\/\/jonpult.ch\/wp-content\/uploads\/2025\/10\/halbierungsinitiative_some_de_hero.png-1024x439.webp\" alt=\"\" class=\"wp-image-5618\" srcset=\"https:\/\/jonpult.ch\/wp-content\/uploads\/2025\/10\/halbierungsinitiative_some_de_hero.png-1024x439.webp 1024w, https:\/\/jonpult.ch\/wp-content\/uploads\/2025\/10\/halbierungsinitiative_some_de_hero.png-300x129.webp 300w, https:\/\/jonpult.ch\/wp-content\/uploads\/2025\/10\/halbierungsinitiative_some_de_hero.png-768x329.webp 768w, https:\/\/jonpult.ch\/wp-content\/uploads\/2025\/10\/halbierungsinitiative_some_de_hero.png-50x21.webp 50w, https:\/\/jonpult.ch\/wp-content\/uploads\/2025\/10\/halbierungsinitiative_some_de_hero.png-117x50.webp 117w, https:\/\/jonpult.ch\/wp-content\/uploads\/2025\/10\/halbierungsinitiative_some_de_hero.png-100x43.webp 100w, https:\/\/jonpult.ch\/wp-content\/uploads\/2025\/10\/halbierungsinitiative_some_de_hero.png-233x100.webp 233w, https:\/\/jonpult.ch\/wp-content\/uploads\/2025\/10\/halbierungsinitiative_some_de_hero.png-640x275.webp 640w, https:\/\/jonpult.ch\/wp-content\/uploads\/2025\/10\/halbierungsinitiative_some_de_hero.png.webp 1401w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Quelle: www.operation-libero.ch<\/figcaption><\/figure>\n\n\n\n<p>In den H\u00e4nden weniger Konzerne liegt heute mehr Macht \u00fcber Information als je zuvor. Nationalr\u00e4tin Jacqueline Badran hat es k\u00fcrzlich auf den Punkt gebracht: Tech-Giganten kontrollieren, filtern und kuratieren Nachrichten, setzen Algorithmen \u00fcber redaktionellen Sinn \u2013 und bestimmen damit, was wir \u00fcberhaupt noch wahrnehmen k\u00f6nnen. Ihre Absicht ist entweder maximaler Profit oder, wie im Fall von Elon Musk, das Durchsetzen einer rechten Agenda. Die Demokratie steht unter Druck. Auch in der Schweiz.<\/p>\n\n\n\n<p>Umso unverst\u00e4ndlicher, dass unser Land ausgerechnet jetzt dar\u00fcber diskutiert, ob wir unsere wichtigste mediale Infrastruktur halbieren wollen. Die sogenannte Halbierungsinitiative der SVP, \u00fcber die wir bald abstimmen, will die Haushaltsabgabe f\u00fcr Radio und Fernsehen senken und den Beitrag der Unternehmen ganz streichen. Das klingt sympathisch und harmlos \u2013 ist aber brandgef\u00e4hrlich. Denn das Budget der SRG w\u00fcrde dadurch halbiert.<\/p>\n\n\n\n<p><strong>Eine eigentliche Anti-SRG-Initiative<\/strong><\/p>\n\n\n\n<p>Was das bedeutet? Einen R\u00fcckzug aus den Regionen. Den Verlust mehrsprachiger Berichterstattung. Das Ausd\u00fcnnen von Angeboten wie \u00abTelesguard\u00bb, \u00abIl Quotidiano\u00bb, \u00abInfrarouge\u00bb oder \u00abEcho der Zeit\u00bb. Den Abbau journalistischer Pr\u00e4senz in der Fl\u00e4che. Graub\u00fcnden w\u00fcrde faktisch RTR und das Romanische sein Fernsehen und grosse Teile seines Radios verlieren. Unter dem Strich g\u00e4be es eine massive Schw\u00e4chung des Service public. In einem Land mit vier Sprachregionen, gelebtem F\u00f6deralismus und starker Zivilgesellschaft ist das nichts weniger als ein Angriff auf den Zusammenhalt.<\/p>\n\n\n\n<p>Die SRG ist nicht perfekt. Aber sie ist einzigartig \u2013 und notwendig. Sie ist die einzige Institution, die t\u00e4glich aus allen Regionen in allen vier Landessprachen berichtet. Sie verbindet, was sonst auseinanderdriften w\u00fcrde. Sie bildet ab, was nicht laut ist, aber relevant. Und sie geh\u00f6rt niemandem ausser uns allen. Keine Partei, kein Konzern, kein Clan, kein Oligarch hat direkten Zugriff auf ihre Informationen. Gerade deshalb ist sie ein Dorn im Auge all jener, die Journalismus kontrollieren, Wahrheiten manipulieren und die demokratische Debatte dominieren wollen.<\/p>\n\n\n\n<p><strong>Information ist Macht<\/strong><\/p>\n\n\n\n<p>Das ist kein Zufall. Die Initiative reiht sich ein in eine internationale Kampagne gegen den \u00f6ffentlich-rechtlichen Rundfunk. Ob in Deutschland durch die AfD, in Ungarn durch Orban oder in den USA durch Trumps Rechte \u2013 \u00fcberall ist das Ziel dasselbe: unabh\u00e4ngige Medien zum Schweigen bringen. Auch bei der SVP-Initiative geht es nicht um Entlastung der Bev\u00f6lkerung. Es geht um Macht \u00fcber Information.<\/p>\n\n\n\n<p>Doch eine Demokratie ohne informierte \u00d6ffentlichkeit verliert ihr Fundament. \u00d6ffentlich-rechtliche Medien wurden nach dem Zweiten Weltkrieg gegr\u00fcndet, um genau das zu verhindern: Sie sollten eine vielf\u00e4ltige, faktenbasierte \u00d6ffentlichkeit sichern, unabh\u00e4ngig von Parteien und Konzernen. Heute brauchen wir sie dringender denn je. Denn wo sie schwach sind, \u00fcbernehmen Algorithmen, Emp\u00f6rung und Propaganda.<\/p>\n\n\n\n<p><strong>Keine Demokratie ohne starke Medien<\/strong><\/p>\n\n\n\n<p>Die Schweiz darf nicht auf diesen gef\u00e4hrlichen Kurs einschwenken. Wenn wir die SRG halbieren, verlieren wir mehr als ein paar Sendungen. Wir verlieren ein St\u00fcck unserer demokratischen Infrastruktur. Wir verlieren die F\u00e4higkeit, uns selbst zu erz\u00e4hlen. Und wir \u00fcberlassen das Feld jenen, die \u00d6ffentlichkeit als Gesch\u00e4ftsmodell oder Machtinstrument betrachten.<\/p>\n\n\n\n<p>Die Schweiz braucht starke Schweizer Medien. F\u00fcr ihren Zusammenhalt. F\u00fcr ihre Demokratie. F\u00fcr ihre Unabh\u00e4ngigkeit.<\/p>\n\n\n\n<p><em>Dieser Text ist 30. Oktober 2025 als Gastkommentar im B\u00fcndner Tagblatt erschienen.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den H\u00e4nden weniger Konzerne liegt heute mehr Macht \u00fcber Information als je zuvor. Nationalr\u00e4tin Jacqueline Badran hat es k\u00fcrzlich auf den Punkt gebracht: Tech-Giganten kontrollieren, filtern und kuratieren Nachrichten, setzen Algorithmen \u00fcber redaktionellen Sinn \u2013 und bestimmen damit, was wir \u00fcberhaupt noch wahrnehmen k\u00f6nnen. Ihre Absicht ist entweder maximaler Profit oder, wie im Fall von Elon Musk, das Durchsetzen einer rechten Agenda. Die Demokratie steht unter Druck. Auch in der Schweiz.<\/p>\n","protected":false},"author":1,"featured_media":5618,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"wds_primary_category":1,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/jonpult.ch\/it\/wp-json\/wp\/v2\/posts\/5612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jonpult.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jonpult.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/it\/wp-json\/wp\/v2\/comments?post=5612"}],"version-history":[{"count":4,"href":"https:\/\/jonpult.ch\/it\/wp-json\/wp\/v2\/posts\/5612\/revisions"}],"predecessor-version":[{"id":5623,"href":"https:\/\/jonpult.ch\/it\/wp-json\/wp\/v2\/posts\/5612\/revisions\/5623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/it\/wp-json\/wp\/v2\/media\/5618"}],"wp:attachment":[{"href":"https:\/\/jonpult.ch\/it\/wp-json\/wp\/v2\/media?parent=5612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jonpult.ch\/it\/wp-json\/wp\/v2\/categories?post=5612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jonpult.ch\/it\/wp-json\/wp\/v2\/tags?post=5612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}