{"id":2894,"date":"2023-02-01T17:31:00","date_gmt":"2023-02-01T16:31:00","guid":{"rendered":"https:\/\/jonpult.ch\/de\/?p=2894"},"modified":"2025-09-05T13:09:41","modified_gmt":"2025-09-05T11:09:41","slug":"abstimmung-18-juni-diesmal-gewinnt-das-klima","status":"publish","type":"post","link":"https:\/\/jonpult.ch\/de\/abstimmung-18-juni-diesmal-gewinnt-das-klima\/","title":{"rendered":"Abstimmung 18. Juni: Diesmal gewinnt das Klima"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-1024x683.jpg.webp\" alt=\"\" class=\"wp-image-2896\" srcset=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-1024x683.jpg.webp 1024w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-300x200.jpg.webp 300w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-768x513.jpg.webp 768w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-1536x1025.jpg.webp 1536w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-2048x1367.jpg.webp 2048w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-1200x801.jpg.webp 1200w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-50x33.jpg.webp 50w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-75x50.jpg.webp 75w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-100x67.jpg.webp 100w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-150x100.jpg.webp 150w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-959x640.jpg.webp 959w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-640x427.jpg.webp 640w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-1151x768.jpg.webp 1151w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-1618x1080.jpg.webp 1618w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2023\/02\/SPS_Klimabeutel_Visualisierung_BildSP_DE-1920x1281.jpg.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Quelle: SP Schweiz<\/figcaption><\/figure>\n\n\n\n<p>Das Nein zum CO2-Gesetz im Sommer 2021 steckt vielen \u00f6kologisch denkenden B\u00fcrgerinnen und B\u00fcrgern noch immer in den Knochen. Die damalige Vorlage war ein grosser klimapolitischer Kompromiss, der viele Bereiche abdeckte und mit verschiedenen Vorschriften, F\u00f6rderungen und Lenkungsmassnahmen unsere Treibhausgasemissionen bis 2030 um die H\u00e4lfte senken sollte. Es scheiterte knapp an einem Referendum der \u00d6l- und Gaslobby. \u00dcber die Gr\u00fcnde dieses Neins wurde viel geschrieben. Die Gleichzeitigkeit der Abstimmung mit den beiden Agrar-Initiativen sowie die Schwierigkeit, als ungerecht empfundene Lenkungsmechanismen zu erkl\u00e4ren, d\u00fcrften die beiden wichtigsten gewesen sein. Doch das Sinnieren \u00fcber die Ursachen der Schlappe bringt nicht viel. Die Schweiz braucht lieber gestern als heute grosse klimapolitische Fortschritte!<\/p>\n\n\n\n<p>Darum hat die SP zusammen mit den Gr\u00fcnen die Klimafonds-Initiative lanciert. Sie begreift die vollst\u00e4ndige Dekarbonisierung der Schweiz bis 2050 als Generationenprojekt, welches riesige Investitionen in den Umbau unserer Wirtschaft sowie in die Aus- und Weiterbildung unserer Bev\u00f6lkerung erfordert. W\u00e4hrend unsere Eltern und Grosseltern die AHV erschaffen, die ETH gegr\u00fcndet und die NEAT gebaut haben, wollen und m\u00fcssen wir die Schweiz in einem Vierteljahrhundert klimaneutral machen. Ein grossz\u00fcgig gespiesener Klimafonds soll die Finanzierung dieser Herkulesaufgabe sichern. Dar\u00fcber werden wir mittelfristig abstimmen.<\/p>\n\n\n\n<p>Kurzfristig haben die fortschrittlichen Kr\u00e4fte im Parlament einen guten Gegenvorschlag zur Gletscher-Initiative gezimmert. Nur das wichtige Netto-Null-Ziel in die Verfassung zu schreiben, ist angesichts der sich zuspitzenden Klimakrise nicht genug. Unser Land braucht Sofortmassnahmen zur Reduktion der Treibhausemissionen. Und wir m\u00fcssen uns schnell von den \u00d6l- und Gaslieferungen aus dubiosen Staaten unabh\u00e4ngig machen. Darum brachte SP-Fraktionschef Roger Nordmann erfolgreich die Idee ein, den gesetzlichen Gegenvorschlag mit hochwirksamen Investitionshilfen zu erg\u00e4nzen. Schliesslich best\u00e4tigen auch Expertinnen und Experten, dass zus\u00e4tzliche Gelder f\u00fcr den raschen Heizungsersatz, f\u00fcr Geb\u00e4udesanierungen und f\u00fcr den Einsatz klimaschonender Technologien in Unternehmen die gr\u00f6sste und vor allem die schnellste Wirkung haben. \u00dcber die kommenden zehn Jahre werden daf\u00fcr 3.2 Milliarden Franken bereitgestellt. So schaffen wir einen grossen Schritt in Richtung Klimaneutralit\u00e4t von Geb\u00e4uden und Wirtschaft.<\/p>\n\n\n\n<p>Das von SP, Gr\u00fcnen, Gr\u00fcnliberalen, Mitte und FDP unterst\u00fctze \u00abBundesgesetz \u00fcber die Ziele im Klimaschutz, die Innovation und die St\u00e4rkung der Energiesicherheit\u00bb bring den Klimaschutz voran, schafft Arbeitspl\u00e4tze und macht uns unabh\u00e4ngiger von \u00d6l- und Gasimporten. Verliererinnen oder Verlierer gibt es keine.<\/p>\n\n\n\n<p>Trotzdem hat die SVP das Referendum dagegen ergriffen \u2013 mit fadenscheinigen Gr\u00fcnden. Statt die Klimakrise endlich ernst zu nehmen und die Versorgungssicherheit der Schweiz zu st\u00e4rken, macht sie mit populistischen Parolen das Gesch\u00e4ft der \u00d6l- und Gaslobby. Doch die Bev\u00f6lkerung wird sich bei der Abstimmung am 18. Juni nicht \u00fcber den Tisch ziehen lassen. Die Argumente sprechen eine zu klare Sprache. Diesmal gewinnt das Klima!<\/p>\n\n\n\n<p><em>Dieser Text ist am 1. Februar 2023 als Kolumne in der S\u00fcdostschweiz erschienen.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Nein zum CO2-Gesetz im Sommer 2021 steckt vielen \u00f6kologisch denkenden B\u00fcrgerinnen und B\u00fcrgern noch immer in den Knochen. Die damalige Vorlage war ein grosser klimapolitischer Kompromiss, der viele Bereiche abdeckte und mit verschiedenen Vorschriften, F\u00f6rderungen und Lenkungsmassnahmen unsere Treibhausgasemissionen bis 2030 um die H\u00e4lfte senken sollte. Es scheiterte knapp an einem Referendum der \u00d6l- und Gaslobby. \u00dcber die Gr\u00fcnde dieses Neins wurde viel geschrieben. Die Gleichzeitigkeit der Abstimmung mit den beiden Agrar-Initiativen sowie die Schwierigkeit, als ungerecht empfundene Lenkungsmechanismen zu erkl\u00e4ren, d\u00fcrften die beiden wichtigsten gewesen sein. Doch das Sinnieren \u00fcber die Ursachen der Schlappe bringt nicht viel. Die Schweiz braucht lieber gestern als heute grosse klimapolitische Fortschritte!<\/p>\n","protected":false},"author":1,"featured_media":2896,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"wds_primary_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts\/2894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/comments?post=2894"}],"version-history":[{"count":3,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts\/2894\/revisions"}],"predecessor-version":[{"id":5504,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts\/2894\/revisions\/5504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/media\/2896"}],"wp:attachment":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/media?parent=2894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/categories?post=2894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/tags?post=2894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}