{"id":2751,"date":"2022-10-26T12:42:55","date_gmt":"2022-10-26T10:42:55","guid":{"rendered":"https:\/\/jonpult.ch\/de\/?p=2751"},"modified":"2025-09-05T13:13:00","modified_gmt":"2025-09-05T11:13:00","slug":"beste-gesundheit-bezahlbar-fuer-alle","status":"publish","type":"post","link":"https:\/\/jonpult.ch\/de\/beste-gesundheit-bezahlbar-fuer-alle\/","title":{"rendered":"Beste Gesundheit, bezahlbar f\u00fcr alle"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img decoding=\"async\" src=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg-1024x576.jpeg.webp\" alt=\"\" class=\"wp-image-2753\" width=\"1024\" height=\"576\" srcset=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg-1024x576.jpeg.webp 1024w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg-300x169.jpeg.webp 300w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg-768x432.jpeg.webp 768w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg-50x28.jpeg.webp 50w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg-89x50.jpeg.webp 89w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg-100x56.jpeg.webp 100w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg-178x100.jpeg.webp 178w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg-1138x640.jpeg.webp 1138w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg-640x360.jpeg.webp 640w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg-1920x1080.jpeg.webp 1920w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2022\/10\/Praemienanstieg.jpeg.webp 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Quelle: Twitter-Feed SP Schweiz<\/figcaption><\/figure>\n\n\n\n<p>Die Schweiz hat eines der besten Gesundheitssysteme. Aber auch eines der teuersten der Welt. J\u00e4hrlich werden \u00fcber 80\u202fMilliarden Franken darin umgesetzt, rund 12\u202fProzent unserer gesamten Wirtschaftsleistung. Grunds\u00e4tzlich ist das ein gutes Zeichen. Wir leben l\u00e4nger und oft besser, haben Zugang zu modernsten Therapien und Medikamenten, das medizinische Fachpersonal ist bestens qualifiziert (wenn auch im Fall der Pflege unterbezahlt!) und unsere Spit\u00e4ler wirken in vielen F\u00e4llen fast wie sch\u00f6ne Hotels. Zudem ist eine Volkswirtschaft sympathischer, die eine Verbesserung der Gesundheit anstrebt statt einer Aufbl\u00e4hung des Finanzsektors oder den Ausbau der R\u00fcstungsindustrie.<\/p>\n\n\n\n<p>Nat\u00fcrlich gibt es auch im Gesundheitswesen Sparpotenzial. Handlungsbedarf besteht bei den \u00fcberh\u00f6hten Medikamentenpreisen, den \u00fcbertriebenen Tarifen gewisser Spezialisten, den hohen Verwaltungskosten der Krankenversicherungen oder bei den oft dysfunktionalen marktwirtschaftlichen Anreizen.<\/p>\n\n\n\n<p>Trotzdem sind nicht die Gesamtkosten unseres Gesundheitswesens das Hauptproblem, sondern deren Verteilung. Denn sowohl die zu hohen Pr\u00e4mien als auch die selbst zu tragenden Zahlungen zum Beispiel f\u00fcr Franchisen, Selbstbehalte, Medikamente oder Zahnbehandlungen sind f\u00fcr immer mehr Haushalte kaum noch zu tragen. In keinem anderen OECD-Land sind die Eigenleistungen der B\u00fcrgerinnen und B\u00fcrger h\u00f6her. Diese individuellen Gesundheitskosten sind neben den Mieten die gr\u00f6ssten Kaufkraftfresser f\u00fcr die Schweizer Mittelschicht.<\/p>\n\n\n\n<p>Hier muss die \u00abBerner Politik\u00bb ansetzen, wenn sie auf der Seite der Bev\u00f6lkerung stehen will. Und zwar nicht, indem sie Leistungen k\u00fcrzt und so noch st\u00e4rker in Richtung Zweiklassenmedizin steuert. Schon heute verzichten gem\u00e4ss Erhebung des Schweizer Gesundheitsobservatoriums rund 11\u202fProzent der Bev\u00f6lkerung aus Kostengr\u00fcnden auf einen Arztbesuch, obwohl dieser medizinisch sinnvoll w\u00e4re. Ein besch\u00e4mender Befund f\u00fcr die Schweiz!<\/p>\n\n\n\n<p>Was die Politik dringend angehen muss, ist eine sozialere Finanzierung des Systems. Trotz (zu) bescheidener Pr\u00e4mienverbilligung ist die Belastung f\u00fcr viele Familien sehr hoch. Im Durchschnitt m\u00fcssen Mittelschichtsfamilien rund 15\u202fProzent des Haushaltseinkommens f\u00fcr Standardpr\u00e4mien bezahlen. Angesichts der aktuellen Inflation und der erneuten Pr\u00e4mienexplosion wird sich diese unhaltbare Situation im n\u00e4chsten Jahr noch versch\u00e4rfen. Der Kaufkraftverlust f\u00fchrt auch dazu, dass Menschen mit wenig Geld noch \u00f6fter auf Arztbesuche verzichten und so auch noch mit ihrer Gesundheit bezahlen. Das ist nicht akzeptabel.<\/p>\n\n\n\n<p>Darum hat die SP schon 2019 die Pr\u00e4mien-Entlastungs-Initiative lanciert, die aktuell im Parlament behandelt wird. Sie verpflichtet Kantone und Bund, die Pr\u00e4mienverbilligungen so auszubauen, dass kein Haushalt mehr als 10\u202fProzent seines verf\u00fcgbaren Einkommens f\u00fcr die Krankenkassenpr\u00e4mien bezahlen muss. Der Nationalrat hat den Handlungsbedarf erkannt und beantragt einen substanziellen Gegenvorschlag, der die Bev\u00f6lkerung um Milliarden pro Jahr entlasten w\u00fcrde. Es liegt nun am St\u00e4nderat, die Bed\u00fcrfnisse unserer Mittelschicht anzuerkennen. Tut er es nicht, wird das Volk an der Urne f\u00fcr Entlastung sorgen. Denn beste Gesundheit muss in der reichen Schweiz f\u00fcr alle erschwinglich sein.<\/p>\n\n\n\n<p><em>Dieser Text ist am 26. Oktober 2022 als Kolumne in der S\u00fcdostschweiz erschienen.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Schweiz hat eines der besten Gesundheitssysteme. Aber auch eines der teuersten der Welt. J\u00e4hrlich werden \u00fcber 80\u202fMilliarden Franken darin umgesetzt, rund 12\u202fProzent unserer gesamten Wirtschaftsleistung. Grunds\u00e4tzlich ist das ein gutes Zeichen. Wir leben l\u00e4nger und oft besser, haben Zugang zu modernsten Therapien und Medikamenten, das medizinische Fachpersonal ist bestens qualifiziert (wenn auch im Fall der Pflege unterbezahlt!) und unsere Spit\u00e4ler wirken in vielen F\u00e4llen fast wie sch\u00f6ne Hotels. Zudem ist eine Volkswirtschaft sympathischer, die eine Verbesserung der Gesundheit anstrebt statt einer Aufbl\u00e4hung des Finanzsektors oder den Ausbau der R\u00fcstungsindustrie.<\/p>\n<p>Nat\u00fcrlich gibt es auch im Gesundheitswesen Sparpotenzial. Handlungsbedarf besteht bei den \u00fcberh\u00f6hten Medikamentenpreisen, den \u00fcbertriebenen Tarifen gewisser Spezialisten, den hohen Verwaltungskosten der Krankenversicherungen oder bei den oft dysfunktionalen marktwirtschaftlichen Anreizen.<\/p>\n","protected":false},"author":1,"featured_media":2753,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"wds_primary_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts\/2751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/comments?post=2751"}],"version-history":[{"count":2,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts\/2751\/revisions"}],"predecessor-version":[{"id":5509,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts\/2751\/revisions\/5509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/media\/2753"}],"wp:attachment":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/media?parent=2751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/categories?post=2751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/tags?post=2751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}