{"id":2234,"date":"2021-05-05T08:26:46","date_gmt":"2021-05-05T06:26:46","guid":{"rendered":"https:\/\/jonpult.ch\/de\/?p=2234"},"modified":"2025-09-05T13:26:59","modified_gmt":"2025-09-05T11:26:59","slug":"co2-gesetz-keine-benzinpreis-hinterwaeldler","status":"publish","type":"post","link":"https:\/\/jonpult.ch\/de\/co2-gesetz-keine-benzinpreis-hinterwaeldler\/","title":{"rendered":"CO2-Gesetz: Keine Benzinpreis-Hinterw\u00e4ldler"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-1024x683.jpg.webp\" alt=\"\" class=\"wp-image-2236\" srcset=\"https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-1024x683.jpg.webp 1024w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-300x200.jpg.webp 300w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-768x512.jpg.webp 768w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-1536x1024.jpg.webp 1536w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-2048x1366.jpg.webp 2048w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-1200x800.jpg.webp 1200w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-50x33.jpg.webp 50w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-75x50.jpg.webp 75w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-100x67.jpg.webp 100w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-150x100.jpg.webp 150w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-960x640.jpg.webp 960w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-640x427.jpg.webp 640w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-1152x768.jpg.webp 1152w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-1620x1080.jpg.webp 1620w, https:\/\/jonpult.ch\/wp-content\/smush-webp\/2021\/05\/Web_Alpeninitiative_PK_Ja_CO2_Gesetz_5592-1920x1280.jpg.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Jon Pult, Pr\u00e4sident Verein Alpen-Initiative, an der Pressekonferenz \/ Live-Stream Verein Alpen-Initiative, Lancierung Ja-Kampagne &#8222;Ja zum CO2-Gesetz&#8220;. Guttannen BE, 20. April 2021. Foto: Mattias Nutt<\/figcaption><\/figure>\n\n\n\n<p>Das CO2-Gesetz ist kein vision\u00e4rer Wurf. Aber es sorgt daf\u00fcr, dass die Schweiz die Verpflichtungen des Pariser Klimaschutz-Abkommens erf\u00fcllt. Bei einem Ja reduzieren wir unseren CO2-Ausstoss bis 2030 um 50 Prozent gegen\u00fcber 1990. F\u00fcr das Klima und damit auch f\u00fcr die Zukunft der Alpen als Lebensraum ist das existenziell. Ein Nein w\u00e4re klimapolitisch katastrophal und wirtschaftlich eine verpasste Chance.<\/p>\n\n\n\n<p>Die Parteien SP, FDP, Mitte, Gr\u00fcne und Gr\u00fcnliberale, die meisten Wirtschaftsverb\u00e4nde, alle Umweltorganisationen und unz\u00e4hlige B\u00fcrgerinnen und B\u00fcrger engagieren sich darum f\u00fcr ein Ja. Nur die SVP ist der Erd\u00f6l-Lobby auf den Leim gekrochen. Damit verteidigen ausgerechnet die selbsternannten Patrioten die Pfr\u00fcnde der ausl\u00e4ndischen \u00d6l-Konzerne. F\u00fcr Sie wie f\u00fcr die Erdgasverk\u00e4ufer geht es um nicht weniger als 8 Milliarden Franken pro Jahr. So viel gibt die Schweiz j\u00e4hrlich f\u00fcr den Import von fossiler Energie aus.<\/p>\n\n\n\n<p>Mit dem CO2-Gesetz reduzieren wir diese wirtschaftliche Abh\u00e4ngigkeit. Jeder Franken, der nicht in zweifelhafte Regimes wie Kasachstan, Russland oder Libyen fliesst, schafft hier Wertsch\u00f6pfung und Arbeitspl\u00e4tze. Denn das Gesetz f\u00f6rdert notwendige Investitionen in der Schweiz und in Graub\u00fcnden. Wir werden die Energieeffizienz unserer Geb\u00e4ude und Infrastrukturen verbessern sowie mehr erneuerbare Energie produzieren. Dabei kommt gerade Graub\u00fcnden zugute, dass die Energie in Form von Wasser und Sonnenschein kostenlos vorhanden ist. Dies im Gegensatz zum \u00d6l, das teuer eingekauft werden muss.<\/p>\n\n\n\n<p>Die vom Temperaturanstieg besonders betroffenen Bergkantone erhalten mit dem im Gesetz neu geschaffenen Klimafonds auch Gelder, um sich mit Schutzbauten besser gegen Naturgefahren wie Bergst\u00fcrze, Murg\u00e4nge und Steinschl\u00e4ge zu sch\u00fctzen. Weiter werden die Sanierung von Geb\u00e4uden, Ladestationen f\u00fcr Elektroautos, die Beschaffung von Elektrobussen oder die Planung und Finanzierung von Fernw\u00e4rmenetzen gef\u00f6rdert. Alles Zukunftschancen f\u00fcr unsere B\u00fcndner Wirtschaft.<\/p>\n\n\n\n<p>Und das Beste daran: Die Kosten der Klimaschutzmassnahmen sind moderat und fair verteilt. Mehr als die H\u00e4lfte der Gelder aus der CO2-Abgabe auf Brennstoffe und aus der Flugticketabgabe wird \u00fcber eine Verbilligung der Krankenkassenpr\u00e4mien pro Kopf an die Bev\u00f6lkerung zur\u00fcckverteilt. Familien und wir in den Bergen profitieren \u00fcberdurchschnittlich davon. Denn wir fliegen deutlich weniger als die Bev\u00f6lkerung im Unterland. Und der Anteil der schon heute erneuerbaren Heizungen ist in Graub\u00fcnden deutlich h\u00f6her als in den grossen St\u00e4dten und Agglomerationen.<\/p>\n\n\n\n<p>Ausserdem bekommen wir die Folgen der steigenden Temperaturen zuallererst zu sp\u00fcren. Die Naturereignisse nehmen bei uns zu, nicht im Unterland. Darum ist Klimaschutz auch ein Gebot der Gerechtigkeit gegen\u00fcber der Bergbev\u00f6lkerung. Umso w\u00fctender macht es mich, wenn die Gegner des CO2-Gesetzes uns Berglerinnen und Bergler wie Hinterw\u00e4ldler behandeln, denen ein paar Rappen Benzinpreis wichtiger sind als der Klimaschutz. Diese Respektlosigkeit lassen wir uns nicht bieten. Mit einem deutlichen Ja zum CO2-Gesetz zeigen wir der Erd\u00f6l-Lobby, dass wir Berglerinnen und Bergler uns nicht instrumentalisieren lassen.<\/p>\n\n\n\n<p><em>Dieser Text ist am 5. Mai 2021 als Kolumne in der S\u00fcdostschweiz erschienen.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das CO2-Gesetz ist kein vision\u00e4rer Wurf. Aber es sorgt daf\u00fcr, dass die Schweiz die Verpflichtungen des Pariser Klimaschutz-Abkommens erf\u00fcllt. Bei einem Ja reduzieren wir unseren CO2-Ausstoss bis 2030 um 50 Prozent gegen\u00fcber 1990. F\u00fcr das Klima und damit auch f\u00fcr die Zukunft der Alpen als Lebensraum ist das existenziell. Ein Nein w\u00e4re klimapolitisch katastrophal und wirtschaftlich eine verpasste Chance.<\/p>\n<p>Die Parteien SP, FDP, Mitte, Gr\u00fcne und Gr\u00fcnliberale, die meisten Wirtschaftsverb\u00e4nde, alle Umweltorganisationen und unz\u00e4hlige B\u00fcrgerinnen und B\u00fcrger engagieren sich darum f\u00fcr ein Ja. Nur die SVP ist der Erd\u00f6l-Lobby auf den Leim gekrochen. Damit verteidigen ausgerechnet die selbsternannten Patrioten die Pfr\u00fcnde der ausl\u00e4ndischen \u00d6l-Konzerne. F\u00fcr Sie wie f\u00fcr die Erdgasverk\u00e4ufer geht es um nicht weniger als 8 Milliarden Franken pro Jahr. So viel gibt die Schweiz j\u00e4hrlich f\u00fcr den Import von fossiler Energie aus.<\/p>\n","protected":false},"author":1,"featured_media":2236,"comment_status":"open","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"wds_primary_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts\/2234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/comments?post=2234"}],"version-history":[{"count":3,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts\/2234\/revisions"}],"predecessor-version":[{"id":5534,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/posts\/2234\/revisions\/5534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/media\/2236"}],"wp:attachment":[{"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/media?parent=2234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/categories?post=2234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jonpult.ch\/de\/wp-json\/wp\/v2\/tags?post=2234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}